{"id":33146,"date":"2020-04-24T13:35:25","date_gmt":"2020-04-24T05:35:25","guid":{"rendered":"https:\/\/www.upowertek.com\/courant-dappel-du-pilote-de-led-et-quantite-de-mcb\/"},"modified":"2022-12-10T13:26:30","modified_gmt":"2022-12-10T05:26:30","slug":"courant-dappel-du-pilote-de-led-et-quantite-de-mcb","status":"publish","type":"post","link":"https:\/\/www.upowertek.com\/fr\/courant-dappel-du-pilote-de-led-et-quantite-de-mcb\/","title":{"rendered":"Courant d&rsquo;appel du pilote de LED et quantit\u00e9 de MCB"},"content":{"rendered":"\n<p>Le courant d&rsquo;appel dans la lumi\u00e8re LED est un domaine qui continue d&rsquo;\u00eatre une pr\u00e9occupation dans l&rsquo;\u00e9clairage LED. Cependant, la v\u00e9rit\u00e9 est que le courant d&rsquo;appel se produit non seulement dans les LED, mais \u00e9galement dans l&rsquo;ensemble du concept d&rsquo;alimentation. Il est courant qu&rsquo;un MCB se d\u00e9clenche. Alors maintenant, voyons ce que signifient le courant d&rsquo;appel et le MCB, et comment calculer le nombre d&rsquo;alimentations pouvant \u00eatre connect\u00e9es \u00e0 un MCB.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Calculateur de courant d&rsquo;appel LED<\/h2>\n\n<p>Si vous souhaitez uniquement conna\u00eetre la quantit\u00e9 de pilotes de LED connect\u00e9s \u00e0 un MCB, vous pouvez utiliser le formulaire que nous avons con\u00e7u pour vous, tapez simplement le courant d&rsquo;appel, la dur\u00e9e d&rsquo;impulsion et le courant d&rsquo;entr\u00e9e, puis choisissez le type de MCB et vous obtiendrez le r\u00e9sultat.<\/p>\n\n          \n\n          <style>@media (max-width:480px){#cp_calculatedfieldsf_pform_1{min-height:2033px;}}@media (max-width:768px){#cp_calculatedfieldsf_pform_1{min-height:1067px;}}@media (max-width:1024px){#cp_calculatedfieldsf_pform_1{min-height:809px;}}@media (min-width:1024px){#cp_calculatedfieldsf_pform_1{min-height:771px;}}<\/style><form name=\"cp_calculatedfieldsf_pform_1\" id=\"cp_calculatedfieldsf_pform_1\" action=\"https:\/\/www.upowertek.com\/fr\/courant-dappel-du-pilote-de-led-et-quantite-de-mcb\/\" method=\"post\" enctype=\"multipart\/form-data\" onsubmit=\"return fbuilderjQuery.fbuilder.doValidate(this);\" class=\"cff-form no-prefetch  cff-form-6 cp_cff_letter\"  data-nonce=\"aa544bc5cd\">\n<input type=\"hidden\" name=\"cp_calculatedfieldsf_pform_psequence\" value=\"_1\" \/>\n<input type=\"hidden\" name=\"cp_calculatedfieldsf_id\" value=\"6\" \/>\n<input type=\"hidden\" name=\"cp_ref_page\" value=\"https:\/\/www.upowertek.com\/fr\" \/>\n<pre style=\"display:none !important;\"><script data-category=\"functional\" type=\"text\/javascript\">form_structure_1=[[{\"form_identifier\":\"\",\"name\":\"fieldname2\",\"shortlabel\":\"\",\"index\":0,\"ftype\":\"fnumber\",\"userhelp\":\"Get this data from the LED driver or lamp datasheet\",\"audiotutorial\":\"\",\"userhelpTooltip\":true,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"Max. Inrush current (A)\",\"predefined\":\"\",\"predefinedClick\":false,\"required\":true,\"exclude\":false,\"readonly\":false,\"numberpad\":false,\"spinner\":false,\"size\":\"small\",\"thousandSeparator\":\"\",\"decimalSymbol\":\".\",\"min\":\"\",\"max\":\"\",\"formatDynamically\":false,\"dformat\":\"number\",\"formats\":[\"digits\",\"number\",\"percent\"],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname3\",\"shortlabel\":\"\",\"index\":1,\"ftype\":\"fnumber\",\"userhelp\":\"50% peak, can be found in the LED driver datasheet, please convert it to T50 if it's T10 showed in the datasheet.\",\"audiotutorial\":\"\",\"userhelpTooltip\":true,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"Pulse Duration T50 (us)\",\"predefined\":\"\",\"predefinedClick\":false,\"required\":true,\"exclude\":false,\"readonly\":false,\"numberpad\":false,\"spinner\":false,\"size\":\"small\",\"thousandSeparator\":\"\",\"decimalSymbol\":\".\",\"min\":\"30\",\"max\":\"2000\",\"formatDynamically\":false,\"dformat\":\"number\",\"formats\":[\"digits\",\"number\",\"percent\"],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname4\",\"shortlabel\":\"\",\"index\":2,\"ftype\":\"fnumber\",\"userhelp\":\"Use the output power of the LED driver to divide efficiency firstly to get the input power, then divide input voltage 230Vac to get the input current\",\"audiotutorial\":\"\",\"userhelpTooltip\":true,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"Input Current 230Vac (A)\",\"predefined\":\"\",\"predefinedClick\":false,\"required\":true,\"exclude\":false,\"readonly\":false,\"numberpad\":false,\"spinner\":false,\"size\":\"small\",\"thousandSeparator\":\"\",\"decimalSymbol\":\".\",\"min\":\"\",\"max\":\"\",\"formatDynamically\":false,\"dformat\":\"number\",\"formats\":[\"digits\",\"number\",\"percent\"],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname6\",\"shortlabel\":\"\",\"index\":3,\"ftype\":\"fdropdown\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"MCB Type\",\"size\":\"small\",\"required\":true,\"exclude\":false,\"toSubmit\":\"text\",\"merge\":0,\"choiceSelected\":\"\",\"select2\":false,\"multiple\":false,\"vChoices\":1,\"showDep\":false,\"choices\":[\"B\",\"C\",\"D\"],\"optgroup\":[false,false,false],\"choicesVal\":[\"3\",\"5\",\"10\"],\"choicesDep\":[[],[],[]],\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"fieldname7\",\"shortlabel\":\"\",\"index\":4,\"ftype\":\"fdropdown\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"MCB Rated Current\",\"size\":\"small\",\"required\":true,\"exclude\":false,\"toSubmit\":\"text\",\"merge\":0,\"choiceSelected\":\"\",\"select2\":false,\"multiple\":false,\"vChoices\":1,\"showDep\":false,\"choices\":[\"10A\",\"16A\",\"25A\",\"32A\"],\"optgroup\":[false,false,false,false],\"choicesVal\":[\"10\",\"16\",\"25\",\"32\"],\"choicesDep\":[[],[],[],[]],\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname1\",\"shortlabel\":\"\",\"index\":5,\"ftype\":\"fCalculated\",\"userhelp\":\"It's calculated based on the pulse duaration you input. The proof factor K can also be found in the MCB datasheet.\",\"audiotutorial\":\"\",\"userhelpTooltip\":true,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"Proof Factor K\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"small\",\"eq\":\"2.446\\\/pow(fieldname3\\\/1000,1.0582)\\n\",\"min\":\"1\",\"max\":\"100\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\"\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"hidefield\":false,\"fBuild\":{},\"parent\":\"\"},{\"form_identifier\":\"\",\"name\":\"separator1\",\"shortlabel\":\"\",\"index\":6,\"ftype\":\"fSectionBreak\",\"userhelp\":\"\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"The field below will show the quantity of LED drivers can be connected to one MCB\",\"fBuild\":{},\"parent\":\"\"},{\"dependencies\":[{\"rule\":\"\",\"complex\":false,\"fields\":[\"\"]}],\"form_identifier\":\"\",\"name\":\"fieldname5\",\"shortlabel\":\"\",\"index\":7,\"ftype\":\"fCalculated\",\"userhelp\":\"These calculated values are based on MCB S200 series manufactured by ABB. It's better to have at least 80% margin by multiply the result with 0.8\",\"audiotutorial\":\"\",\"userhelpTooltip\":false,\"tooltipIcon\":false,\"csslayout\":\"\",\"title\":\"LED Driver Quantity\",\"predefined\":\"\",\"required\":false,\"exclude\":false,\"size\":\"small\",\"eq\":\"floor(min(fieldname1*fieldname6*fieldname7\\\/fieldname2, fieldname7\\\/fieldname4))\",\"min\":\"\",\"max\":\"\",\"suffix\":\"\",\"prefix\":\"\",\"decimalsymbol\":\".\",\"groupingsymbol\":\"\",\"readonly\":true,\"currency\":false,\"noEvalIfManual\":true,\"formatDynamically\":false,\"hidefield\":false,\"fBuild\":{},\"parent\":\"\"}],{\"0\":{\"title\":\"Inrush Current Calculator\",\"description\":\"Calculate how many LED drivers can be connected to a MCB\",\"formlayout\":\"left_aligned\",\"formtemplate\":\"cp_cff_letter\",\"evalequations\":1,\"evalequationsevent\":2,\"loading_animation\":0,\"autocomplete\":1,\"persistence\":0,\"animate_form\":0,\"customstyles\":\"\"},\"formid\":\"cp_calculatedfieldsf_pform_1\"}];<\/script><\/pre>\n<div id=\"fbuilder\">\n\t\t<div id=\"fbuilder_1\">\n\t\t<div id=\"formheader_1\"><\/div>\n\t\t<div id=\"fieldlist_1\"><\/div>\n\t\t<div class=\"clearer\"><\/div>\n\t<\/div>\n<\/div>\n\t<div id=\"cp_subbtn_1\" class=\"cp_subbtn\" style=\"display:none;\"><\/div><div class=\"clearer\"><\/div>\n\t<input type=\"hidden\" id=\"_cpcff_public_nonce\" name=\"_cpcff_public_nonce\" value=\"8b4d0e4d98\" \/><input type=\"hidden\" name=\"_wp_http_referer\" value=\"\/fr\/wp-json\/wp\/v2\/posts\/33146\" \/><input type=\"hidden\" name=\"cff_form_start_time\" value=\"C9CH4CeNctOKthzzBRJ3Eg==\"><\/form>\n\t\n          \n\n        \n\n<p>Veuillez continuer \u00e0 lire si vous souhaitez savoir comment le num\u00e9ro est obtenu.<\/p>\n\n<div style=\"height:46px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Qu&rsquo;est-ce que le courant d&rsquo;appel du pilote de LED<\/h2>\n\n<p>\n          <strong>Le courant d&rsquo;appel du pilote de LED est le courant d&rsquo;entr\u00e9e instantan\u00e9 maximal (courte dur\u00e9e) circulant dans le pilote de LED lors de la mise sous tension de l&rsquo;alimentation. <\/strong>\n        <\/p>\n\n<p>Le courant d&rsquo;appel porte d&rsquo;autres noms tels que la surtension d&rsquo;enclenchement et le courant de surtension d&rsquo;entr\u00e9e. Ce n&rsquo;est pas une nouvelle que les pilotes de LED subissent des courants d&rsquo;appel \u00e9lev\u00e9s qui vont jusqu&rsquo;\u00e0 100 fois le courant continu nominal.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-large\"><img fetchpriority=\"high\" decoding=\"async\" width=\"568\" height=\"291\" src=\"http:\/\/upowertek.com\/wp-content\/uploads\/2020\/04\/inrush.png\" alt=\"\" class=\"wp-image-6033\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/inrush.png 568w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/inrush-300x154.png 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/inrush-400x205.png 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/inrush-450x231.png 450w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/inrush-367x188.png 367w\" sizes=\"(max-width: 568px) 100vw, 568px\" \/><figcaption class=\"wp-element-caption\">Courant d&rsquo;appel<\/figcaption><\/figure>\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\" style=\"background-color:#f6f6f6\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"404\" height=\"580\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/Inrush-current-and-MCB.png\" alt=\"courant d'appel et mcb\" class=\"wp-image-10540\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/Inrush-current-and-MCB.png 404w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/Inrush-current-and-MCB-209x300.png 209w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/Inrush-current-and-MCB-400x574.png 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/Inrush-current-and-MCB-367x527.png 367w\" sizes=\"(max-width: 404px) 100vw, 404px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-large-font-size\"><strong><strong>T\u00e9l\u00e9charger<\/strong><\/strong> <strong>le fichier<\/strong> PDF <\/p>\n\n\n\n<p class=\"has-text-align-left\"> Pour vous faire gagner du temps, nous avons \u00e9galement pr\u00e9par\u00e9 une version PDF contenant tout le contenu de cette page, ne laissez que votre email et vous recevrez imm\u00e9diatement l&rsquo;e-book. <strong> <\/strong><\/p>\n\n\n\n          \n\n          <div class=\"ml-embedded\" data-form=\"9gzBcu\"><\/div>\n          \n\n        \n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Qu&rsquo;est-ce qui cause le courant d&rsquo;appel dans les pilotes de LED\u00a0?<\/h2>\n\n<p>Le courant d&rsquo;appel se produit dans tout appareil qui tire du courant alternatif de la source d&rsquo;alimentation, tel qu&rsquo;un transformateur, des moteurs \u00e9lectriques, des pilotes de LED, etc.<\/p>\n\n<p>Les pilotes de LED ont des condensateurs qui produisent une charge minimale \u00e0 une \u00e9chelle standard avec une alimentation \u00e9lectrique. Par cons\u00e9quent, les pilotes de LED n\u00e9cessitent un courant initial \u00e9lev\u00e9 pour charger le condensateur, ce qui entra\u00eene un courant d&rsquo;appel. De plus, le temps n\u00e9cessaire au courant d&rsquo;entr\u00e9e pour charger le condensateur est tr\u00e8s rapide, cr\u00e9ant une surtension \u00e0 l&rsquo;enclenchement.<\/p>\n\n<p>Ayons une vue plus claire en utilisant le graphique de l&rsquo;heure actuelle <em>ci-dessous.m le graphique<\/em> , <\/p>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img decoding=\"async\" width=\"592\" height=\"266\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/current-time-graph.png\" alt=\"graphique de l'heure actuelle\" class=\"wp-image-10476\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/current-time-graph.png 592w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/current-time-graph-300x135.png 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/current-time-graph-400x180.png 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/current-time-graph-367x165.png 367w\" sizes=\"(max-width: 592px) 100vw, 592px\" \/><\/figure>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<p>on voit qu&rsquo;il faut quelques millisecondes pour que le courant d&rsquo;entr\u00e9e atteigne un r\u00e9gime permanent. Mais en raison de la vitesse de charge du condensateur par le courant d&rsquo;entr\u00e9e, le courant augmente jusqu&rsquo;\u00e0 un courant de cr\u00eate (d\u00e9sign\u00e9 par 6A). Puis, apr\u00e8s un certain temps, le courant chute au courant stable (indiqu\u00e9 par 5A). Ainsi, le courant qui existe \u00e0 la courte diff\u00e9rence de temps est un courant d&rsquo;appel. <\/p>\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Signification et identification du courant d&rsquo;appel<\/h2>\n\n<p>La question qui pourrait vous traverser l&rsquo;esprit pourrait \u00eatre ; Pourquoi parle-t-on de courants d&rsquo;appel ? Ou pourquoi est-ce une telle pr\u00e9occupation dans l&rsquo;industrie de l&rsquo;\u00e9clairage ? Donc, pour apporter des r\u00e9ponses, nous voulons voir l&rsquo;importance des courants d&rsquo;appel dans les pilotes de LED.<\/p>\n\n<p>Les effets du courant d&rsquo;appel sur les pilotes de LED ne sont pas attrayants. Les ant\u00e9c\u00e9dents montrent que les courants d&rsquo;appel sont plus une nuisance qu&rsquo;un alli\u00e9 du syst\u00e8me LED. Comme le rapport du courant d&rsquo;appel \u00e0 celui du courant permanent est \u00e9lev\u00e9, il en r\u00e9sulte une surtension qui provoque ce qui suit\u00a0;<\/p>\n\n<ul class=\"wp-block-list\">\n<li>D\u00e9clenchement de l&rsquo;interrupteur d&rsquo;alimentation<\/li>\n\n\n\n<li>Fusibles grill\u00e9s<\/li>\n\n\n\n<li>Dommages au disjoncteur<\/li>\n\n\n\n<li>D\u00e9faillance du syst\u00e8me de gradation de la lumi\u00e8re<\/li>\n\n\n\n<li>Contacts de relais de soudage<\/li>\n<\/ul>\n\n<p>Dans l&rsquo;ensemble, le courant d&rsquo;appel repr\u00e9sente un grand danger pour les pilotes de LED car il peut endommager le pilote et r\u00e9duire l&rsquo;efficacit\u00e9.<\/p>\n\n<p>La t\u00e2che suivante de cette section est de vous aider \u00e0 identifier un courant d&rsquo;appel. Nous pouvons r\u00e9aliser cet exploit en d\u00e9crivant les caract\u00e9ristiques des courants d&rsquo;appel.<\/p>\n\n<ul class=\"wp-block-list\">\n<li>Ils sont instantan\u00e9s\u00a0: se produisent au moment o\u00f9 le pilote de LED est aliment\u00e9<\/li>\n\n\n\n<li>Poss\u00e8de un courant sup\u00e9rieur au courant nominal du pilote<\/li>\n\n\n\n<li>Ont g\u00e9n\u00e9ralement une plage de tension de 120V-240V<\/li>\n\n\n\n<li>Dure peu de temps, mais assez efficace pour causer des dommages<\/li>\n\n\n\n<li>Il fait la moyenne pendant un demi-cycle<\/li>\n<\/ul>\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Comment calculer le courant d&rsquo;appel\u00a0?<\/h2>\n\n<p>Lors du calcul du courant d&rsquo;appel, vous devez tenir compte de facteurs tels que le temps (dur\u00e9e), le courant de cr\u00eate et la forme de la forme d&rsquo;onde. Rappelons tout d&rsquo;abord les ph\u00e9nom\u00e8nes de courant d&rsquo;appel que nous repr\u00e9sentons sur un graphique. Vous verrez que lorsque le pilote de LED est aliment\u00e9, le courant d&rsquo;entr\u00e9e atteint un courant de cr\u00eate avant de revenir au courant de r\u00e9gime permanent.<\/p>\n\n<p>Le m\u00e9canisme ci-dessus donne lieu \u00e0 une forme d&rsquo;onde dont la forme d\u00e9pend du niveau de courant d&rsquo;appel variable. A partir de ces formes d&rsquo;onde, nous pouvons maintenant calculer les courants d&rsquo;appel. Chaque forme de la forme d&rsquo;onde a une formule appropri\u00e9e pour calculer le courant d&rsquo;appel.<\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<p> Voyons le tableau ci-dessous\uff1a <\/p>\n\n\n\n<p>O\u00f9;<\/p>\n\n\n\n<p>Ip = Courant de cr\u00eate<\/p>\n\n\n\n<p>Ia = Courant permanent<\/p>\n\n\n\n<p>t = Temps<\/p>\n\n\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p> Alternativement, vous pouvez mesurer le courant d&rsquo;appel avec des appareils tels que le multim\u00e8tre num\u00e9rique, la pince amp\u00e8rem\u00e9trique et l&rsquo;analyseur de qualit\u00e9 de l&rsquo;alimentation. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"300\" height=\"411\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Circuit-Breaker-App-Note.webp\" alt=\"note d'application sur les disjoncteurs\" class=\"wp-image-10514\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Circuit-Breaker-App-Note.webp 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Circuit-Breaker-App-Note-219x300.webp 219w\" sizes=\"(max-width: 300px) 100vw, 300px\" \/><\/figure>\n<\/div>\n<\/div>\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Facteurs qui influencent les courants d&rsquo;appel des pilotes de LED<\/h2>\n\n<p>Les facteurs qui influencent le courant d&rsquo;appel comprennent la tension d&rsquo;entr\u00e9e, la temp\u00e9rature et la charge. Voyons comment ils r\u00e9agissent aux courants d&rsquo;appel<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Tension d&rsquo;entr\u00e9e<\/strong>\u00a0: les courants d&rsquo;appel augmentent \u00e0 mesure que la tension d&rsquo;entr\u00e9e augmente \u00e9galement.<\/li>\n\n\n\n<li><strong>Condensateur de masse interne<\/strong>\u00a0: c&rsquo;est la principale raison pour laquelle un courant d&rsquo;appel \u00e9lev\u00e9 se produit. Plus la capacit\u00e9 est \u00e9lev\u00e9e, plus la valeur du courant d&rsquo;appel est \u00e9lev\u00e9e.<\/li>\n\n\n\n<li><strong>Temp\u00e9rature<\/strong> : lorsqu&rsquo;il y a une temp\u00e9rature \u00e9lev\u00e9e, la r\u00e9sistance devient faible, entra\u00eenant plus de courant d&rsquo;appel. L&rsquo;inverse est le cas \u00e0 une temp\u00e9rature inf\u00e9rieure du syst\u00e8me.<\/li>\n<\/ul>\n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"486\" height=\"304\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2016\/10\/150w-open-frame.png\" alt=\"Driver LED 150W &#xE0; cadre ouvert\" class=\"wp-image-1377\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2016\/10\/150w-open-frame.png 486w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2016\/10\/150w-open-frame-300x188.png 300w\" sizes=\"(max-width: 486px) 100vw, 486px\" \/><figcaption class=\"wp-element-caption\">Condensateur en vrac dans le pilote de LED<\/figcaption><\/figure>\n\n<h2 class=\"wp-block-heading\">Comment limiter le courant d&rsquo;appel dans les pilotes de LED<\/h2>\n\n<p>En suivant cet article, nous voyons que le courant d&rsquo;appel est un fait valable et pr\u00e9sente un grand danger pour les pilotes de LED. Par cons\u00e9quent, la meilleure \u00e9tape consiste \u00e0 explorer les moyens de limiter les courants d&rsquo;appel afin de pr\u00e9server et d&rsquo;am\u00e9liorer les pilotes de LED.<\/p>\n\n<p>Mais avant d&rsquo;examiner les m\u00e9thodes de limitation, nous devons comprendre les facteurs qui aident \u00e0 d\u00e9terminer la m\u00e9thode de limitation appropri\u00e9e.<\/p>\n\n<ul class=\"wp-block-list\">\n<li><strong>Temps de commutation :<\/strong> Lorsqu&rsquo;il y a un temps de commutation rapide, l&rsquo;utilisation de la m\u00e9thode du coefficient de temp\u00e9rature n\u00e9gatif (NTC) devient inadapt\u00e9e. La technique n&rsquo;est pas adapt\u00e9e car le NTC n&rsquo;a pas le temps de se refroidir, ce qui va augmenter la temp\u00e9rature et, \u00e0 son tour, augmenter le courant d&rsquo;appel.<\/li>\n\n\n\n<li><strong>Capacit\u00e9 de charge\u00a0:<\/strong> un syst\u00e8me \u00e0 haute capacit\u00e9 aura besoin d&rsquo;un courant transitoire \u00e9lev\u00e9 lorsque l&rsquo;alimentation est allum\u00e9e. Par cons\u00e9quent, un circuit de d\u00e9marrage progressif est id\u00e9al pour limiter le courant d&rsquo;appel.<\/li>\n\n\n\n<li><strong>Ph\u00e9nom\u00e8nes de courant faible basse tension :<\/strong> se produisent lorsque la charge et la source d&rsquo;alimentation sont pr\u00e9sentes dans le m\u00eame circuit. L&rsquo;approche id\u00e9ale est l&rsquo;utilisation d&rsquo;un r\u00e9gulateur de tension.<\/li>\n\n\n\n<li><strong>\u00c9valuation du courant de r\u00e9gime permanent<\/strong> : l&rsquo;approche NTC est adapt\u00e9e dans ce cas car un courant de r\u00e9gime permanent \u00e9lev\u00e9 a tendance \u00e0 augmenter la temp\u00e9rature.<\/li>\n<\/ul>\n\n<p>Termin\u00e9 et d\u00e9poussi\u00e9r\u00e9 avec les facteurs, il est maintenant temps d&rsquo;examiner les m\u00e9thodes de limitation appropri\u00e9es.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"693\" height=\"446\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Inrush-Current-1.jpg\" alt=\"courant d'appel 1\" class=\"wp-image-10512\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Inrush-Current-1.jpg 693w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Inrush-Current-1-600x386.jpg 600w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Inrush-Current-1-300x193.jpg 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Inrush-Current-1-640x412.jpg 640w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Inrush-Current-1-400x257.jpg 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Inrush-Current-1-367x236.jpg 367w\" sizes=\"(max-width: 693px) 100vw, 693px\" \/><\/figure>\n\n<div style=\"height:40px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">La m\u00e9thode du coefficient de temp\u00e9rature n\u00e9gatif (NTC)<\/h3>\n\n<div class=\"wp-block-columns are-vertically-aligned-center is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<p>L&rsquo;approche NTC porte \u00e9galement le nom de thermistance. Il utilise le principe de changement de r\u00e9sistance \u00e0 diff\u00e9rentes temp\u00e9ratures. C&rsquo;est-\u00e0-dire qu&rsquo;il offre une r\u00e9sistance \u00e9lev\u00e9e \u00e0 basse temp\u00e9rature et une faible r\u00e9sistance \u00e0 haute temp\u00e9rature.<\/p>\n\n\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>La NTC et les entr\u00e9es sont en s\u00e9rie\u00a0; par cons\u00e9quent, lorsqu&rsquo;il y a une alimentation \u00e9lectrique, le NTC donne une r\u00e9sistance \u00e9lev\u00e9e, diminuant le courant d&rsquo;appel.<\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"579\" height=\"311\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current.png\" alt=\"courant d'appel\" class=\"wp-image-10478\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current.png 579w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current-300x161.png 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current-400x215.png 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current-367x197.png 367w\" sizes=\"(max-width: 579px) 100vw, 579px\" \/><\/figure>\n<\/div>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Circuit de d\u00e9marrage progressif<\/h3>\n\n<p>Il porte \u00e9galement le nom de circuit \u00e0 retard, qui est principalement pr\u00e9sent dans les r\u00e9gulateurs de tension. Le circuit prend en charge la modification du temps de mont\u00e9e de la sortie, qui \u00e0 son tour diminue le courant de sortie. De plus, un circuit de d\u00e9marrage progressif aide \u00e0 r\u00e9duire le courant d&rsquo;appel.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h3 class=\"wp-block-heading\">Disjoncteurs miniatures (MCB)<\/h3>\n\n<p>Un disjoncteur miniature est un appareil \u00e9lectromagn\u00e9tique qui porte un mat\u00e9riau isolant moul\u00e9 complet. La fonction principale de cet appareil est de commuter le circuit. Cela signifie ouvrir automatiquement le circuit (qui se connecte au courant) lorsque le courant traversant le circuit d\u00e9passe une valeur ou une limite d\u00e9finie. Le MCB est con\u00e7u pour prot\u00e9ger le c\u00e2ble en aval de l&rsquo;appareil contre les surcharges et les courts-circuits, en \u00e9vitant d&rsquo;endommager les c\u00e2bles et les \u00e9quipements. L&rsquo;appareil peut \u00eatre allum\u00e9 ou \u00e9teint manuellement, tout comme les interrupteurs standard chaque fois que n\u00e9cessaire.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-large is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"http:\/\/upowertek.com\/wp-content\/uploads\/2020\/04\/MCB.jpg\" alt=\"\" class=\"wp-image-6066\" width=\"659\" height=\"428\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB.jpg 878w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-600x390.jpg 600w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-300x195.jpg 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-768x499.jpg 768w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-640x415.jpg 640w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-400x260.jpg 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-367x238.jpg 367w\" sizes=\"(max-width: 659px) 100vw, 659px\" \/><figcaption class=\"wp-element-caption\">Disjoncteurs C16<\/figcaption><\/figure>\n\n<p>Les disjoncteurs miniatures sont d\u00e9clench\u00e9s en raison des limitations du NTC ou de la thermistance dans un cas o\u00f9 ils ne peuvent pas limiter le courant d&rsquo;appel. Le principe du MCB est qu&rsquo;il se d\u00e9clenche une fois qu&rsquo;il d\u00e9tecte un sc\u00e9nario de court-circuit de surcharge. Ainsi, le MCB agit comme une barri\u00e8re lorsqu&rsquo;il se d\u00e9clenche avant que l&rsquo;exc\u00e8s d&rsquo;\u00e9nergie ne circule dans les pilotes tout en maintenant la lumi\u00e8re.<\/p>\n\n<h4 class=\"wp-block-heading\">Types de MCB<\/h4>\n\n<p>Il existe 3 types de MCB, Type B, Type C et Type D, et la vitesse \u00e0 laquelle ils se d\u00e9clenchent d\u00e9pend du niveau de surcharge et est g\u00e9n\u00e9ralement d\u00e9termin\u00e9e par un dispositif thermique dans le MCB. Une courbe de d\u00e9clenchement typique du MCB montre le temps n\u00e9cessaire pour qu&rsquo;un disjoncteur se d\u00e9clenche \u00e0 un niveau de surintensit\u00e9 donn\u00e9, comme ci-dessous.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1007\" height=\"752\" src=\"http:\/\/upowertek.com\/wp-content\/uploads\/2020\/04\/mcb.png\" alt=\"\" class=\"wp-image-6034\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/mcb.png 1007w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/mcb-600x448.png 600w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/mcb-300x224.png 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/mcb-768x574.png 768w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/mcb-640x478.png 640w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/mcb-400x300.png 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/mcb-367x274.png 367w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/mcb-200x150.png 200w\" sizes=\"(max-width: 1007px) 100vw, 1007px\" \/><\/figure>\n\n<p>Ces courbes diff\u00e8rent d&rsquo;un fabricant \u00e0 l&rsquo;autre et d&rsquo;un type \u00e0 l&rsquo;autre. En r\u00e8gle g\u00e9n\u00e9rale, la courbe MCB de type B a une plage de fonctionnement de 3 \u00e0 5 In, le type C a 5 \u00e0 10 In et le type D a 10-14 In selon les fiches techniques de la s\u00e9rie ABB S201M la plus couramment utilis\u00e9e. <\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h4 class=\"wp-block-heading\">\n          <strong>Caract\u00e9ristiques de d\u00e9clenchement des MCB<\/strong>\n        <\/h4>\n\n<p>Le MCB fonctionne en se d\u00e9clenchant lorsqu&rsquo;un circuit est surcharg\u00e9 ou lorsqu&rsquo;un court-circuit s&rsquo;est produit dans le syst\u00e8me et a un courant nominal tel que 6A ou 10A selon son utilisation pr\u00e9vue, c&rsquo;est-\u00e0-dire pour les b\u00e2timents r\u00e9sidentiels, commerciaux, industriels ou publics. Le MCB est d\u00e9clench\u00e9 dans deux conditions, le courant de r\u00e9gime permanent et le courant instantan\u00e9 \u00e9galement appel\u00e9 courant d&rsquo;appel.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1004\" height=\"615\" src=\"http:\/\/upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-5.png\" alt=\"\" class=\"wp-image-6040\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-5.png 1004w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-5-600x368.png 600w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-5-300x184.png 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-5-768x470.png 768w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-5-640x392.png 640w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-5-400x245.png 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-5-367x225.png 367w\" sizes=\"(max-width: 1004px) 100vw, 1004px\" \/><\/figure>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p>La capacit\u00e9 du MCB \u00e0 se d\u00e9clencher d\u00e9pend de la dur\u00e9e du courant et de son amplitude. Voyons un graphique qui montre les caract\u00e9ristiques de chaque MCB. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"400\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-B-type-MCB-.webp\" alt=\"courbe de d&#xE9;clenchement pour disjoncteur de type b \" class=\"wp-image-10515\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-B-type-MCB-.webp 500w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-B-type-MCB--300x240.webp 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-B-type-MCB--400x320.webp 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-B-type-MCB--367x294.webp 367w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\">Courbe de d\u00e9clenchement pour MCB de type B <\/figcaption><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<p> La courbe bleue est le courant nominal \u00e0 une dur\u00e9e donn\u00e9e \u00e0 partir des figures ci-dessus, et la zone de la case indique la zone de d\u00e9clenchement instantan\u00e9. <\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"500\" height=\"400\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-C-type-MCB-.webp\" alt=\"courbe de d&#xE9;clenchement pour mcb de type c \" class=\"wp-image-10516\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-C-type-MCB-.webp 500w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-C-type-MCB--300x240.webp 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-C-type-MCB--400x320.webp 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-C-type-MCB--367x294.webp 367w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\">Courbe de d\u00e9clenchement pour mMCB de type C <\/figcaption><\/figure>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-vertically-aligned-top is-layout-flow wp-block-column-is-layout-flow\">\n<p>On peut donc r\u00e9sumer les caract\u00e9ristiques de d\u00e9clenchement \u00e0 l&rsquo;aide du tableau ci-dessous.<\/p>\n\n\n\n<p>Il montre qu&rsquo;un MCB de type C peut supporter deux fois le courant nominal pendant une dur\u00e9e de 850 ms sans d\u00e9clenchement et trois fois le courant nominal pendant 130 ms sans d\u00e9clenchement.<\/p>\n\n\n\n<figure class=\"wp-block-image size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"315\" height=\"151\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/a-type-C-MCB-1.png\" alt=\"un type c mcb 1\" class=\"wp-image-10522\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/a-type-C-MCB-1.png 315w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/a-type-C-MCB-1-300x144.png 300w\" sizes=\"(max-width: 315px) 100vw, 315px\" \/><\/figure>\n\n\n\n<p><\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-vertically-aligned-center is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"inherit-container-width wp-block-group is-layout-constrained wp-block-group-is-layout-constrained\">\n<figure class=\"wp-block-image size-full is-resized\"><img loading=\"lazy\" decoding=\"async\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-D-type-MCB-.webp\" alt=\"courbe de d&#xE9;clenchement pour disjoncteur de type d \" class=\"wp-image-10518\" width=\"500\" height=\"400\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-D-type-MCB-.webp 500w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-D-type-MCB--300x240.webp 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-D-type-MCB--400x320.webp 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/Tripping-curve-for-D-type-MCB--367x294.webp 367w\" sizes=\"(max-width: 500px) 100vw, 500px\" \/><figcaption class=\"wp-element-caption\">courbe de d\u00e9clenchement pour disjoncteur de type d <\/figcaption><\/figure>\n<\/div>\n<\/div>\n<\/div>\n\n<div class=\"wp-block-columns has-background is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\" style=\"background-color:#f6f6f6\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\">\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<figure class=\"wp-block-image size-full\"><img decoding=\"async\" width=\"404\" height=\"580\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/Inrush-current-and-MCB.png\" alt=\"courant d'appel et mcb\" class=\"wp-image-10540\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/Inrush-current-and-MCB.png 404w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/Inrush-current-and-MCB-209x300.png 209w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/Inrush-current-and-MCB-400x574.png 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/Inrush-current-and-MCB-367x527.png 367w\" sizes=\"(max-width: 404px) 100vw, 404px\" \/><\/figure>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<div style=\"height:48px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p class=\"has-text-align-center has-large-font-size\"><strong>Vous voulez le lire plus tard ?<\/strong> <\/p>\n\n\n\n<p class=\"has-text-align-left\"> Pour vous faire gagner du temps, nous avons \u00e9galement pr\u00e9par\u00e9 une version PDF contenant tout le contenu de cette page, ne laissez que votre email et vous recevrez imm\u00e9diatement l&rsquo;e-book. <strong> <\/strong><\/p>\n\n\n\n          \n\n          <div class=\"ml-embedded\" data-form=\"9gzBcu\"><\/div>\n          \n\n        \n<\/div>\n<\/div>\n<\/div>\n<\/div>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Formule pour calculer la cote MCB n\u00e9cessaire pour le syst\u00e8me<\/h2>\n\n<p><\/p>\n\n<p>Pour conna\u00eetre le nombre de pilotes LED que vous pouvez connecter en parall\u00e8le \u00e0 un seul MCB, vous aurez besoin de l&rsquo;image ci-dessous. La formule pour calculer le nombre de charge du pilote de LED est Min (je <sub>d\u00e9clenche<\/sub> \/je <sub>pilote<\/sub> , je <sub>maintiens<\/sub> \/je <sub>lance)<\/sub> . La valeur est le minimum entre deux valeurs.<\/p>\n\n<div class=\"wp-block-columns is-layout-flex wp-container-core-columns-is-layout-28f84493 wp-block-columns-is-layout-flex\">\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:33.33%\">\n<p>I <sub>d\u00e9clenchement<\/sub> : courant nominal MCB (d\u00e9pend des diff\u00e9rents types de MCB).<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>I <sub>driver<\/sub> : le courant moyen d&rsquo;entr\u00e9e maximal d&rsquo;un driver de LED.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>Je <sub>retiens<\/sub> : le courant nominal instantan\u00e9 du MCB.<\/p>\n\n\n\n<div style=\"height:20px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n\n\n<p>I <sub>inrush<\/sub> : le courant d&rsquo;appel maximum d&rsquo;un driver LED. <\/p>\n<\/div>\n\n\n\n<div class=\"wp-block-column is-layout-flow wp-block-column-is-layout-flow\" style=\"flex-basis:66.66%\">\n<figure class=\"wp-block-image aligncenter size-full\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"372\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/different-types-of-MCB.webp\" alt=\"diff&#xE9;rents types de mcb\" class=\"wp-image-10489\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/different-types-of-MCB.webp 600w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/different-types-of-MCB-300x186.webp 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/different-types-of-MCB-400x248.webp 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/different-types-of-MCB-367x228.webp 367w\" sizes=\"(max-width: 600px) 100vw, 600px\" \/><\/figure>\n<\/div>\n<\/div>\n\n<p>Et la courbe la plus critique pour calculer le nombre de pilotes de LED que vous pouvez mettre en parall\u00e8le est celle ci-dessous. Nous devons trouver le facteur de preuve par rapport \u00e0 la courbe de dur\u00e9e d&rsquo;impulsion \u00e0 partir de la fiche technique du MCB, puis trouver la dur\u00e9e d&rsquo;impulsion \u00e0 partir de la fiche technique du pilote de LED, puis vous pouvez obtenir la valeur du facteur de preuve-K en fonction de la courbe. Obtenez le courant de cr\u00eate d&rsquo;appel \u00e0 partir de la fiche technique du pilote LED. Il existe g\u00e9n\u00e9ralement deux types de dur\u00e9e dans la fiche technique, T50 et T10. T50 signifie la dur\u00e9e entre 50\u00a0% de cr\u00eate et 50\u00a0% de cr\u00eate, T10 signifie la dur\u00e9e entre 10\u00a0% de cr\u00eate et 10\u00a0% de cr\u00eate. Nous utilisons les donn\u00e9es T50 pour le calcul.<\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"999\" height=\"625\" src=\"http:\/\/upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-2.png\" alt=\"\" class=\"wp-image-6037\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-2.png 999w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-2-600x375.png 600w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-2-300x188.png 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-2-768x480.png 768w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-2-640x400.png 640w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-2-400x250.png 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-2-367x230.png 367w\" sizes=\"(max-width: 999px) 100vw, 999px\" \/><\/figure>\n\n<p>Un exemple typique de calcul des charges MCB est pr\u00e9sent\u00e9 ci-dessous. <\/p>\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"572\" height=\"374\" src=\"http:\/\/upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-3.png\" alt=\"\" class=\"wp-image-6038\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-3.png 572w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-3-300x196.png 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-3-400x262.png 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-3-367x240.png 367w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2020\/04\/MCB-cal-3-560x367.png 560w\" sizes=\"(max-width: 572px) 100vw, 572px\" \/><\/figure>\n\n<p>Jusqu&rsquo;\u00e0 pr\u00e9sent, vous avez appris ce qu&rsquo;est le courant d&rsquo;appel et comment calculer le nombre de pilotes de LED pouvant \u00eatre connect\u00e9s \u00e0 un MCB. Si vous avez encore des doutes, vous pouvez nous envoyer un message pour en savoir plus.<\/p>\n\n          \n\n          <div class=\"wp-block-contact-form-7-contact-form-selector\">\n            \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f10070-o1\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"10070\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/posts\/33146#wpcf7-f10070-o1\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"10070\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f10070-o1\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.5\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your Name*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your Email*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"How can we help you?*\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/><br \/>\n<span class=\"wpcf7-form-control-wrap chapter\" data-name=\"chapter\"><input type=\"hidden\" name=\"chapter\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Courant d&#039;appel du pilote de LED et quantit\u00e9 de MCB\"><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap dynamicurl\" data-name=\"dynamicurl\"><input type=\"hidden\" name=\"dynamicurl\" id=\"post-url\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/posts\/33146\"><\/span>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_1\" name=\"_wpcf7_ak_js\" value=\"112\"\/><script>\ndocument.getElementById( \"ak_js_1\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n          <\/div>\n          \n\n        \n\n<div style=\"height:60px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">S\u00e9lection du MCB du pilote de LED uPowerTek<\/h2>\n\n<p>Tout d&rsquo;abord, trouvez le tableau Peak Current-duration de la fiche technique MCB, vous pouvez prendre un <sub>pic<\/sub> comme je <sub>le tiens<\/sub> , ce que nous avons mentionn\u00e9 ci-dessus.<\/p>\n\n<figure class=\"wp-block-table is-style-stripes\"><table class=\"has-dark-color has-text-color has-background\" style=\"background-color:#7ea5ca\"><thead><tr><th class=\"has-text-align-center\" data-align=\"center\">Dur\u00e9e<br\/>[us]<\/th><th class=\"has-text-align-center\" data-align=\"center\">B10 actuel<br\/>[Un <sub>pic<\/sub> ]<\/th><th class=\"has-text-align-center\" data-align=\"center\">B13 actuel<br\/>[Un <sub>pic<\/sub> ]<\/th><th class=\"has-text-align-center\" data-align=\"center\">B16 actuel<br\/>[Un <sub>pic<\/sub> ]<\/th><th class=\"has-text-align-center\" data-align=\"center\">B20 actuel<br\/>[Un <sub>pic<\/sub> ]<\/th><\/tr><\/thead><tbody><tr><td class=\"has-text-align-center\" data-align=\"center\">100<\/td><td class=\"has-text-align-center\" data-align=\"center\">700<\/td><td class=\"has-text-align-center\" data-align=\"center\">910<\/td><td class=\"has-text-align-center\" data-align=\"center\">1120<\/td><td class=\"has-text-align-center\" data-align=\"center\">1400<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">200<\/td><td class=\"has-text-align-center\" data-align=\"center\">260<\/td><td class=\"has-text-align-center\" data-align=\"center\">338<\/td><td class=\"has-text-align-center\" data-align=\"center\">416<\/td><td class=\"has-text-align-center\" data-align=\"center\">520<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">300<\/td><td class=\"has-text-align-center\" data-align=\"center\">177<\/td><td class=\"has-text-align-center\" data-align=\"center\">230.1<\/td><td class=\"has-text-align-center\" data-align=\"center\">283<\/td><td class=\"has-text-align-center\" data-align=\"center\">354<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">400<\/td><td class=\"has-text-align-center\" data-align=\"center\">145<\/td><td class=\"has-text-align-center\" data-align=\"center\">188.5<\/td><td class=\"has-text-align-center\" data-align=\"center\">232<\/td><td class=\"has-text-align-center\" data-align=\"center\">290<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">500<\/td><td class=\"has-text-align-center\" data-align=\"center\">122<\/td><td class=\"has-text-align-center\" data-align=\"center\">158.6<\/td><td class=\"has-text-align-center\" data-align=\"center\">195<\/td><td class=\"has-text-align-center\" data-align=\"center\">244<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">600<\/td><td class=\"has-text-align-center\" data-align=\"center\">110<\/td><td class=\"has-text-align-center\" data-align=\"center\">143<\/td><td class=\"has-text-align-center\" data-align=\"center\">176<\/td><td class=\"has-text-align-center\" data-align=\"center\">220<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">700<\/td><td class=\"has-text-align-center\" data-align=\"center\">102<\/td><td class=\"has-text-align-center\" data-align=\"center\">132.6<\/td><td class=\"has-text-align-center\" data-align=\"center\">163<\/td><td class=\"has-text-align-center\" data-align=\"center\">204<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">800<\/td><td class=\"has-text-align-center\" data-align=\"center\">97<\/td><td class=\"has-text-align-center\" data-align=\"center\">126.1<\/td><td class=\"has-text-align-center\" data-align=\"center\">155<\/td><td class=\"has-text-align-center\" data-align=\"center\">194<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">900<\/td><td class=\"has-text-align-center\" data-align=\"center\">93<\/td><td class=\"has-text-align-center\" data-align=\"center\">120.9<\/td><td class=\"has-text-align-center\" data-align=\"center\">149<\/td><td class=\"has-text-align-center\" data-align=\"center\">186<\/td><\/tr><tr><td class=\"has-text-align-center\" data-align=\"center\">1000<\/td><td class=\"has-text-align-center\" data-align=\"center\">90<\/td><td class=\"has-text-align-center\" data-align=\"center\">117<\/td><td class=\"has-text-align-center\" data-align=\"center\">144<\/td><td class=\"has-text-align-center\" data-align=\"center\">180<\/td><\/tr><\/tbody><\/table><\/figure>\n\n<p>Votre meilleur choix de MCB est celui qui r\u00e9duit le courant de cr\u00eate et la dur\u00e9e des impulsions. Par cons\u00e9quent, uPowerTek a propos\u00e9 une solution con\u00e7ue pour r\u00e9duire le courant d&rsquo;appel dans les pilotes de LED.<\/p>\n\n<div style=\"height:30px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">En fin de compte, \u00e9liminez la difficult\u00e9 de s\u00e9lection MCB<\/h2>\n\n<p><br\/>Lorsque le syst\u00e8me devient plus grand, il devient beaucoup plus difficile de choisir le bon MCB. R\u00e9duisant ainsi le courant d&rsquo;appel du pilote de LED \u00e0 un certain niveau, ce qui rend le calcul de s\u00e9lection uniquement li\u00e9 au courant d&rsquo;entr\u00e9e de fonctionnement normal. La nouvelle conception de pilote de LED uPowerTek r\u00e9duit la valeur de cr\u00eate du courant d&rsquo;appel \u00e0 1\/10 des concurrents, augmentant ainsi consid\u00e9rablement la s\u00e9curit\u00e9 de la s\u00e9lection du MCB.<\/p>\n\n<figure class=\"wp-block-image aligncenter size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"448\" src=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current-peak-1024x448.png\" alt=\"pic de courant d'appel\" class=\"wp-image-10492\" srcset=\"https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current-peak-1024x448.png 1024w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current-peak-600x262.png 600w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current-peak-300x131.png 300w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current-peak-768x336.png 768w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current-peak-640x280.png 640w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current-peak-400x175.png 400w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current-peak-367x160.png 367w, https:\/\/www.upowertek.com\/wp-content\/uploads\/2021\/12\/inrush-current-peak.png 1244w\" sizes=\"(max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n<div style=\"height:49px\" aria-hidden=\"true\" class=\"wp-block-spacer\"><\/div>\n\n<h2 class=\"wp-block-heading\">Derniers mots<\/h2>\n\n<p>Le courant d&rsquo;appel est incontestablement une menace pour les pilotes de LED. Nous voulons tous des pilotes LED efficaces et m\u00eame une dur\u00e9e de vie plus longue pour nos pilotes LED. La bonne nouvelle est que uPowerTek prend en compte tous ces probl\u00e8mes et con\u00e7oit des pilotes de LED avec des syst\u00e8mes qui limitent les courants d&rsquo;appel. Ce fut un parcours remarquable car nous avons maintenant une bonne connaissance du concept de courant d&rsquo;appel. Et n&rsquo;oubliez pas que uPowerTek continue de fournir des connaissances utiles ainsi que des solutions de pilote LED exceptionnelles.<\/p>\n\n<p class=\"has-medium-font-size\"><strong>Contactez-nous maintenant pour demander les pilotes de LED \u00e0 faible courant d&rsquo;appel<\/strong>\u00a0!<\/p>\n\n          \n\n          <div class=\"wp-block-contact-form-7-contact-form-selector\">\n            \n<div class=\"wpcf7 no-js\" id=\"wpcf7-f10070-o2\" lang=\"en-US\" dir=\"ltr\" data-wpcf7-id=\"10070\">\n<div class=\"screen-reader-response\"><p role=\"status\" aria-live=\"polite\" aria-atomic=\"true\"><\/p> <ul><\/ul><\/div>\n<form action=\"\/fr\/wp-json\/wp\/v2\/posts\/33146#wpcf7-f10070-o2\" method=\"post\" class=\"wpcf7-form init\" aria-label=\"Contact form\" novalidate=\"novalidate\" data-status=\"init\">\n<fieldset class=\"hidden-fields-container\"><input type=\"hidden\" name=\"_wpcf7\" value=\"10070\" \/><input type=\"hidden\" name=\"_wpcf7_version\" value=\"6.1.5\" \/><input type=\"hidden\" name=\"_wpcf7_locale\" value=\"en_US\" \/><input type=\"hidden\" name=\"_wpcf7_unit_tag\" value=\"wpcf7-f10070-o2\" \/><input type=\"hidden\" name=\"_wpcf7_container_post\" value=\"0\" \/><input type=\"hidden\" name=\"_wpcf7_posted_data_hash\" value=\"\" \/><input type=\"hidden\" name=\"_wpcf7dtx_version\" value=\"5.0.5\" \/>\n<\/fieldset>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-name\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-text wpcf7-validates-as-required\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your Name*\" value=\"\" type=\"text\" name=\"your-name\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-email\"><input size=\"40\" maxlength=\"400\" class=\"wpcf7-form-control wpcf7-email wpcf7-validates-as-required wpcf7-text wpcf7-validates-as-email\" aria-required=\"true\" aria-invalid=\"false\" placeholder=\"Your Email*\" value=\"\" type=\"email\" name=\"your-email\" \/><\/span>\n<\/p>\n<p><span class=\"wpcf7-form-control-wrap\" data-name=\"your-message\"><textarea cols=\"40\" rows=\"10\" maxlength=\"2000\" class=\"wpcf7-form-control wpcf7-textarea\" aria-invalid=\"false\" placeholder=\"How can we help you?*\" name=\"your-message\"><\/textarea><\/span>\n<\/p>\n<p><input class=\"wpcf7-form-control wpcf7-submit has-spinner\" type=\"submit\" value=\"Send\" \/><br \/>\n<span class=\"wpcf7-form-control-wrap chapter\" data-name=\"chapter\"><input type=\"hidden\" name=\"chapter\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"Courant d&#039;appel du pilote de LED et quantit\u00e9 de MCB\"><\/span><br \/>\n<span class=\"wpcf7-form-control-wrap dynamicurl\" data-name=\"dynamicurl\"><input type=\"hidden\" name=\"dynamicurl\" id=\"post-url\" class=\"wpcf7-form-control wpcf7-hidden wpcf7dtx wpcf7dtx-hidden\" aria-invalid=\"false\" value=\"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/posts\/33146\"><\/span>\n<\/p><p style=\"display: none !important;\" class=\"akismet-fields-container\" data-prefix=\"_wpcf7_ak_\"><label>&#916;<textarea name=\"_wpcf7_ak_hp_textarea\" cols=\"45\" rows=\"8\" maxlength=\"100\"><\/textarea><\/label><input type=\"hidden\" id=\"ak_js_2\" name=\"_wpcf7_ak_js\" value=\"87\"\/><script>\ndocument.getElementById( \"ak_js_2\" ).setAttribute( \"value\", ( new Date() ).getTime() );\n<\/script>\n<\/p><div class=\"wpcf7-response-output\" aria-hidden=\"true\"><\/div>\n<\/form>\n<\/div>\n\n          <\/div>\n          \n\n        \n\n<p> <\/p>\n","protected":false},"excerpt":{"rendered":"<p>Le courant d&rsquo;appel dans la lumi\u00e8re LED est un domaine qui continue d&rsquo;\u00eatre une pr\u00e9occupation dans l&rsquo;\u00e9clairage LED. Cependant, la v\u00e9rit\u00e9 est que le courant d&rsquo;appel se produit non seulement dans les LED, mais \u00e9galement dans l&rsquo;ensemble du concept d&rsquo;alimentation. Il est courant qu&rsquo;un MCB se d\u00e9clenche. Alors maintenant, voyons ce que signifient le courant [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":26949,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_robots_follow":"","_seopress_robots_imageindex":"","_seopress_robots_snippet":"","_seopress_robots_primary_cat":"none","_seopress_robots_breadcrumbs":"","_seopress_robots_freeze_modified_date":"","_seopress_robots_custom_modified_date":"","_seopress_robots_canonical":"","_seopress_social_fb_title":"","_seopress_social_fb_desc":"","_seopress_social_fb_img":"","_seopress_social_fb_img_attachment_id":0,"_seopress_social_fb_img_width":0,"_seopress_social_fb_img_height":0,"_seopress_social_twitter_title":"","_seopress_social_twitter_desc":"","_seopress_social_twitter_img":"","_seopress_social_twitter_img_attachment_id":0,"_seopress_social_twitter_img_width":0,"_seopress_social_twitter_img_height":0,"_seopress_redirections_value":"","_seopress_redirections_enabled":"","_seopress_redirections_enabled_regex":"","_seopress_redirections_logged_status":"tous les deux","_seopress_redirections_param":"","_seopress_redirections_type":301,"_seopress_analysis_target_kw":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[1500],"tags":[],"class_list":{"0":"post-33146","1":"post","2":"type-post","3":"status-publish","4":"format-standard","5":"has-post-thumbnail","7":"category-connaissances"},"_links":{"self":[{"href":"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/posts\/33146","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/comments?post=33146"}],"version-history":[{"count":1,"href":"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/posts\/33146\/revisions"}],"predecessor-version":[{"id":33190,"href":"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/posts\/33146\/revisions\/33190"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/media\/26949"}],"wp:attachment":[{"href":"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/media?parent=33146"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/categories?post=33146"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.upowertek.com\/fr\/wp-json\/wp\/v2\/tags?post=33146"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}